{"id":262,"count":3,"description":"","link":"https:\/\/univation.jp\/universchool\/tag\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\/","name":"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0","slug":"%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0 \u30a2\u30fc\u30ab\u30a4\u30d6 - \u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/univation.jp\/universchool\/tag\/\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0 \u30a2\u30fc\u30ab\u30a4\u30d6 - \u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/univation.jp\/universchool\/tag\/\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\/\" \/>\n<meta property=\"og:site_name\" content=\"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/tag\\\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\\\/\",\"url\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/tag\\\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\\\/\",\"name\":\"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0 \u30a2\u30fc\u30ab\u30a4\u30d6 - \u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/tag\\\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\\\/#breadcrumb\"},\"inLanguage\":\"ja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/tag\\\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/#website\",\"url\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/\",\"name\":\"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0\",\"description\":\"\u672a\u6765\u3078\u3064\u306a\u304c\u308b\u3002\u6210\u7e3e\u3092\u4f38\u3070\u3057\u3001\u53ef\u80fd\u6027\u3082\u5e83\u3052\u308b\u3002\",\"publisher\":{\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/#organization\",\"name\":\"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0\",\"url\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_400x400.jpeg\",\"contentUrl\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_400x400.jpeg\",\"width\":400,\"height\":400,\"caption\":\"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0\"},\"image\":{\"@id\":\"https:\\\/\\\/univation.jp\\\/universchool\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0 \u30a2\u30fc\u30ab\u30a4\u30d6 - \u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/univation.jp\/universchool\/tag\/\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\/","og_locale":"ja_JP","og_type":"article","og_title":"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0 \u30a2\u30fc\u30ab\u30a4\u30d6 - \u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0","og_url":"https:\/\/univation.jp\/universchool\/tag\/\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\/","og_site_name":"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/univation.jp\/universchool\/tag\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\/","url":"https:\/\/univation.jp\/universchool\/tag\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\/","name":"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0 \u30a2\u30fc\u30ab\u30a4\u30d6 - \u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0","isPartOf":{"@id":"https:\/\/univation.jp\/universchool\/#website"},"breadcrumb":{"@id":"https:\/\/univation.jp\/universchool\/tag\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\/#breadcrumb"},"inLanguage":"ja"},{"@type":"BreadcrumbList","@id":"https:\/\/univation.jp\/universchool\/tag\/%e3%83%9e%e3%83%bc%e3%82%b1%e3%83%86%e3%82%a3%e3%83%b3%e3%82%b0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/univation.jp\/universchool\/"},{"@type":"ListItem","position":2,"name":"\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0"}]},{"@type":"WebSite","@id":"https:\/\/univation.jp\/universchool\/#website","url":"https:\/\/univation.jp\/universchool\/","name":"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0","description":"\u672a\u6765\u3078\u3064\u306a\u304c\u308b\u3002\u6210\u7e3e\u3092\u4f38\u3070\u3057\u3001\u53ef\u80fd\u6027\u3082\u5e83\u3052\u308b\u3002","publisher":{"@id":"https:\/\/univation.jp\/universchool\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/univation.jp\/universchool\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/univation.jp\/universchool\/#organization","name":"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0","url":"https:\/\/univation.jp\/universchool\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/univation.jp\/universchool\/#\/schema\/logo\/image\/","url":"https:\/\/univation.jp\/universchool\/wp-content\/uploads\/2022\/01\/logo_400x400.jpeg","contentUrl":"https:\/\/univation.jp\/universchool\/wp-content\/uploads\/2022\/01\/logo_400x400.jpeg","width":400,"height":400,"caption":"\u5b66\u7fd2\u587e\u30e6\u30cb\u30d0\u30fc\u30b9\u30af\u30fc\u30eb in \u5bae\u5d0e\u53f0"},"image":{"@id":"https:\/\/univation.jp\/universchool\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/univation.jp\/universchool\/wp-json\/wp\/v2\/tags\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/univation.jp\/universchool\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/univation.jp\/universchool\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/univation.jp\/universchool\/wp-json\/wp\/v2\/posts?tags=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}